{"id":2837,"date":"2018-12-14T15:51:04","date_gmt":"2018-12-14T15:51:04","guid":{"rendered":"http:\/\/borkyou.com\/?post_type=product&#038;p=2837"},"modified":"2025-04-08T10:55:06","modified_gmt":"2025-04-08T10:55:06","slug":"sesimbra-en-kayak","status":"publish","type":"product","link":"https:\/\/borkyou.com\/es\/tours\/sesimbra-en-kayak\/","title":{"rendered":"Sesimbra en kayak"},"content":{"rendered":"<h1>El Kayak es una de las mejores maneras de descubrir Sesimbra, su Parque Natural y Reserva mar\u00edtima. Te divertir\u00e1s junto a la familia y amigos mientras haces\u00a0 ejercicio agradablemente admirando paisajes \u00fanicos.<\/h1>\n<p>Sesimbra en kayak comienza en el centro BORK &amp; Haliotis en el Puerto de Sesimbra, podr\u00e1s remar por la Bah\u00eda de Sesimbra e ir a lo largo de la preciosa costa del Parque Natural de Arrabida y la Reserva Mar\u00edtima Luiz de Saldanha.<br \/>\nTu gu\u00eda te ayudar\u00e1 a encontrar el camino para explorar los acantilados, cuevas y otras maravillas geol\u00f3gicas. Tendr\u00e1s tiempo para relajarte, admirar las aguas cristalinas y divertirte tomando un snack en Praia do Ribeiro do Cavalo, una de las playas m\u00e1s bonitas de Portugal. \u00a1Tendr\u00e1s tiempo para tomarte un descanso e incluso un concurso de fotograf\u00eda! A continuaci\u00f3n remaremos de vuelta hasta el Puerto de Sesimbra, donde comenz\u00f3 el tour.<\/p>\n<h2>Horario de Sesimbra en kayak<\/h2>\n<p>Puedes unirte por la ma\u00f1ana a las 10am o solicitar otro horario para tu grupo.<\/p>\n<h2>Gu\u00edas de Sesimbra en kayak<\/h2>\n<p>Nuestros gu\u00edas son los profesionales mejor cualificados, certificados por la Federaci\u00f3n portuguesa de Canoa seran los encargados tanto de la seguridad como de la diversi\u00f3n de los clientes. Ellos te estar\u00e1n cuidando constantemente. En m\u00e1s de 30 a\u00f1os de experiencia, nadie ha sufrido una lesi\u00f3n grave en ninguno de los viajes en kayak de BORK.<\/p>\n<table class=\"table table-bordered tours-tabs__table\" style=\"height: 233px;\" width=\"862\">\n<tbody>\n<tr>\n<td><strong>SALIDA\/LUGAR DE LLEGADA<\/strong><\/td>\n<td>Centro BORK\/Haliotis, Puerto de Sesimbra<\/td>\n<\/tr>\n<tr>\n<td><strong>HORA DE SALIDA<\/strong><\/td>\n<td>Le rogamos que llegue 10 minutos antes del comienzo.<\/td>\n<\/tr>\n<tr>\n<td><strong>HORA DE LLEGADA<\/strong><\/td>\n<td>Aproximadamente 3 horas desde la salida.<\/td>\n<\/tr>\n<tr>\n<td><strong>ROPA<\/strong><\/td>\n<td>Trae ropa de ba\u00f1o, camiseta de licra, sombrero\/gorra y crema solar.<\/td>\n<\/tr>\n<tr>\n<td><strong>INCLUIDO<\/strong><\/td>\n<td>\n<table class=\"table table-bordered\" style=\"height: 62px;\" width=\"300\">\n<tbody>\n<tr>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Guia porfesional<\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Todo el material: Kayak, pala, chaleco salvavidas y neopreno.<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Agua y Aperitivo<\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Lugar seguro para tus pertenencias<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td><b>NO INCLUIDO<\/b><\/td>\n<td>\n<table class=\"table table-bordered\" style=\"height: 62px;\" width=\"300\">\n<tbody>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Transporte desde el hotel y vuelta, pero puede ser acordado por separado<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Fotograf\u00edas de la traves\u00eda, que tambien puede ser acordado por separado.<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>La comida no est\u00e1 incluida pero puedes llevarte algo para comer mientras disfrutas de la playa<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"\" data-bm=\"645\">Rema<\/span> <span class=\"\" data-bm=\"647\">en<\/span> <span class=\"\" data-bm=\"649\">medio<\/span> <span class=\"\" data-bm=\"651\">del<\/span> <span class=\"\" data-bm=\"653\">Parque<\/span> <span class=\"\" data-bm=\"655\">Natural<\/span> <span class=\"\" data-bm=\"657\">de<\/span> <span class=\"\" data-bm=\"659\">Arr\u00e1bida<\/span> <span class=\"\" data-bm=\"661\">y<\/span> <span class=\"\" data-bm=\"663\">la<\/span> <span class=\"\" data-bm=\"665\">Reserva<\/span> <span class=\" tta_align\" data-bm=\"667\">Mar\u00edtima<\/span> <span class=\"\" data-bm=\"669\">Luiz<\/span> <span class=\"\" data-bm=\"671\">de<\/span> <span class=\"\" data-bm=\"673\">Saldanha<\/span> <span class=\"\" data-bm=\"675\">con<\/span> <span class=\" \" data-bm=\"677\">excelentes<\/span> <span class=\"\" data-bm=\"679\">gu\u00edas<\/span> <span class=\"\" data-bm=\"681\">de<\/span> <span class=\"\" data-bm=\"683\">kayak<\/span><span class=\"\" data-bm=\"684\">.<\/span> <span class=\"\" data-bm=\"686\">El<\/span><span data-bm=\"687\"> kayak <\/span><span class=\"\" data-bm=\"688\">es<\/span> <span class=\"\" data-bm=\"690\">la<\/span> <span class=\"\" data-bm=\"692\">mejor<\/span> <span class=\"\" data-bm=\"694\">manera<\/span> <span class=\"\" data-bm=\"696\">de<\/span> <span class=\"\" data-bm=\"698\">descubrir<\/span> <span class=\"\" data-bm=\"700\">la<\/span> <span class=\"\" data-bm=\"702\">costa<\/span><span class=\"\" data-bm=\"703\">,<\/span> <span class=\"\" data-bm=\"705\">sus<\/span> <span class=\"\" data-bm=\"707\">aguas<\/span> <span class=\"\" data-bm=\"709\">cristalinas<\/span><span class=\"\" data-bm=\"710\">,<\/span> <span class=\"\" data-bm=\"712\">cuevas<\/span> <span class=\"\" data-bm=\"714\">y<\/span> <span class=\"\" data-bm=\"716\">playas<\/span> <span class=\"\" data-bm=\"718\">escondidas<\/span><span class=\"\" data-bm=\"719\">.<\/span><\/p>\n","protected":false},"featured_media":10259,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[147],"product_tag":[],"class_list":["post-2837","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categorizar","tour_category-ambiente-familiar","tour_category-dependiente-del-tempo","tour_category-piraguismo-kayak","tour_category-seaview-board-es","tour_category-sesimbra-es","tour_category-snacks-incluidos-es","first","instock","taxable","shipping-taxable","purchasable","product-type-tour"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/2837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media\/10259"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media?parent=2837"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_brand?post=2837"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_cat?post=2837"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_tag?post=2837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}