{"id":2865,"date":"2018-12-14T16:01:58","date_gmt":"2019-01-04T17:58:20","guid":{"rendered":"http:\/\/borkyou.com\/?post_type=product&#038;p=2865"},"modified":"2024-01-16T11:40:49","modified_gmt":"2024-01-16T11:40:49","slug":"paseo-en-bicicleta-por-lisboa","status":"publish","type":"product","link":"https:\/\/borkyou.com\/es\/tours\/paseo-en-bicicleta-por-lisboa\/","title":{"rendered":"Paseo en bicicleta por Lisboa"},"content":{"rendered":"<h1>Paseo en bicicleta por Lisboa \u00a1Disfruta de un paseo en bicicleta descubriendo Lisboa y sus principales monumentos!<\/h1>\n<p>Un paseo en bicicleta por Lisboa es la mejor manera de descubrir la ciudad pedaleando por la orilla del r\u00edo Tajo. Iremos en bicicleta de monta\u00f1a desde el centro de Lisboa hasta Bel\u00e9m, donde los grandes navegantes sol\u00edan partir hacia los descubrimientos m\u00e1s incre\u00edbles. Visitar\u00e1s el centro de la ciudad de Lisboa, sus principales plazas y monumentos y recorrer\u00e1s el r\u00edo Tajo desde el muelle hasta Bel\u00e9m. Pasaremos bajo el puente parecido al Puente de San Francisco, el puente rojo renombrado \u00bb25 de Abril\u00bb tras la revoluci\u00f3n de 1974 . Tambi\u00e9n descubrir\u00e1s Bel\u00e9m y sus principales monumentos: Monumento a los Descubridores, Torre de Bel\u00e9m y Monasterio de los Jer\u00f3nimos, donde dejaremos las bicicletas para entrar en la Iglesia de Santa Mar\u00eda donde se albergan las tumbas de Vasco de Gama, el mayor navegante portugu\u00e9s y Luis de Cam\u00f5es, el mayor poeta portugu\u00e9s. La iglesia es, como dice Kubler: \u00abLa realizaci\u00f3n m\u00e1s ambiciosa del medieval tard\u00edo de cubrir el mayor espacio posible con el menor n\u00famero de apoyos\u00bb. Por supuesto, no te perder\u00e1s una parada estrat\u00e9gica en Pasteis de Bel\u00e9m, donde disfrutar\u00e1s de la mejor y m\u00e1s secreta pasteler\u00eda del mundo. \u00a1Simplemente delicioso!<\/p>\n<p>Puedes quedarte en Bel\u00e9m despu\u00e9s del viaje para visitar la zona. El Museo Berardo tiene la mejor colecci\u00f3n de arte moderno y contempor\u00e1neo de Lisboa, compuesto por Dal\u00ed, Picasso, Lichtenstein, Andy Warhol y Marcel Duchamp entre otros muchos artistas.<\/p>\n<h2>Equipo del paseo en bicicleta por Lisboa<\/h2>\n<p>Usamos bicicletas de monta\u00f1a muy c\u00f3modas, perfectas para manejar por el suelo de Lisboa, el cual puede volverse inc\u00f3modo en caso de no tener buenas bicicletas. Los cascos son suministrados, as\u00ed como el agua y aperitivo.<\/p>\n<h2>Reserva el Paseo en bicicleta por Lisboa<\/h2>\n<p>El paseo empieza a las 10am en la Estaci\u00f3n de trenes de Cais do Sodr\u00e9. Puedes solicitar otro horario para tu grupo. Tambi\u00e9n podemos comenzar el paseo cerca de tu hotel. \u00a1Contacta con nosotros!<\/p>\n<table class=\"table table-bordered tours-tabs__table\" style=\"height: 233px;\" width=\"862\">\n<tbody>\n<tr>\n<td><strong>SALIDA\/LUGAR DE LLEGADA<\/strong><\/td>\n<td>Estaci\u00f3n de trenes Cais do Sodr\u00e9 \/ Bel\u00e9m<\/td>\n<\/tr>\n<tr>\n<td><strong>HORA DE SALIDA<\/strong><\/td>\n<td>Le rogamos que llegue 10 minutos antes del comienzo.<\/td>\n<\/tr>\n<tr>\n<td><strong>HORA DE LLEGADA<\/strong><\/td>\n<td>Aproximadamente 2 horas desde la salida.<\/td>\n<\/tr>\n<tr>\n<td><strong>ROPA<\/strong><\/td>\n<td>Ropa y zapatos c\u00f3modos adem\u00e1s de crema solar.<\/td>\n<\/tr>\n<tr>\n<td><strong>INCLUIDO<\/strong><\/td>\n<td>\n<table class=\"table table-bordered\" style=\"height: 62px;\" width=\"300\">\n<tbody>\n<tr>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Gu\u00eda profesional<\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Todo el material: bicicleta de monta\u00f1a y casco.<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Agua<\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Los mejores pasteles del mundo \ud83d\ude42<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td><b>NO INCLUIDO<\/b><\/td>\n<td>\n<table class=\"table table-bordered\" style=\"height: 62px;\" width=\"300\">\n<tbody>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Transporte desde el hotel y vuelta, pero puede ser acordado por separado<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Fotograf\u00edas de la traves\u00eda, que tambien puede ser acordado por separado.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Descubre los principales monumentos de Lisboa mientras vas en bicicleta!<\/p>\n","protected":false},"featured_media":2842,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[147],"product_tag":[],"class_list":["post-2865","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categorizar","tour_category-ciclismo","tour_category-lisboa-es","tour_category-snacks-incluidos-es","first","instock","taxable","shipping-taxable","purchasable","product-type-tour"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/2865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media\/2842"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media?parent=2865"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_brand?post=2865"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_cat?post=2865"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_tag?post=2865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}