{"id":2919,"date":"2018-12-14T15:58:53","date_gmt":"2018-12-14T15:58:53","guid":{"rendered":"http:\/\/borkyou.com\/?post_type=product&#038;p=2919"},"modified":"2024-07-31T00:00:48","modified_gmt":"2024-07-31T00:00:48","slug":"oeiras-en-kayak","status":"publish","type":"product","link":"https:\/\/borkyou.com\/es\/tours\/oeiras-en-kayak\/","title":{"rendered":"Oeiras en Kayak"},"content":{"rendered":"<h1>\u00a1Oeiras en Kayak es la mejor manera de ver la costa de Lisboa, hacer ejercicio agradablemente y divertirse con la familia o amigos!<\/h1>\n<p>Oeiras en Kayak es por lejos el recorrido m\u00e1s popular de Lisboa. Empezando desde la Marina de Oeiras, el \u00faltimo puerto entre el R\u00edo Tajo y el Oc\u00e9ano Atl\u00e1ntico, remar\u00e1s a lo largo de la costa de Lisboa, ver\u00e1s hermosas fortalezas mar\u00edtimas, parar\u00e1s en playa ideal para inmersiones de buceo y por supuesto, \u00a1disfrutar\u00e1s remando! Nuestros gu\u00edas certificados te dar\u00e1n una peque\u00f1a introducci\u00f3n sobre kayak antes de partir. No necesitas ser un palista experimentado, suponemos que la mayor\u00eda de vosotros nunca hab\u00e9is hecho kayak antes. Disfruta del recorrido, sigue las instrucciones del gu\u00eda y por supuesto, \u00a1divi\u00e9rtete!<\/p>\n<h2>Reserva Oeiras en Kayak<\/h2>\n<p>Puedes unirte por la ma\u00f1ana o por la tarde a las 10 am o 2:30pm respectivamente o solicitar otro horario para tu grupo.<\/p>\n<h2>Instructores de Oeiras en Kayak<\/h2>\n<p>Nuestros gu\u00edas son los profesionales mejor cualificados, certificados por la Federaci\u00f3n portuguesa de Canoa, y se encargar\u00e1n tanto de la seguridad como de la diversi\u00f3n de los clientes. Te estar\u00e1n cuidando constantemente. En m\u00e1s de 30 a\u00f1os de experiencia, nadie ha sufrido nunca una lesi\u00f3n grave en ning\u00fan viaje de kayak de BORK.<\/p>\n<table class=\"table table-bordered tours-tabs__table\" style=\"height: 233px;\" width=\"862\">\n<tbody>\n<tr>\n<td><strong>SALIDA\/LUGAR DE LLEGADA<\/strong><\/td>\n<td>Tienda BORK, Oeiras Marina<\/td>\n<\/tr>\n<tr>\n<td><strong>HORA DE SALIDA<\/strong><\/td>\n<td>Rogamos que llegue 10 minutos antes del comienzo.<\/td>\n<\/tr>\n<tr>\n<td><strong>HORA DE LLEGADA<\/strong><\/td>\n<td>Aproximadamente 2 horas desde la salida.<\/td>\n<\/tr>\n<tr>\n<td><strong>ROPA<\/strong><\/td>\n<td>Trae ropa de ba\u00f1o, sombrero\/gorra y crema solar.<\/td>\n<\/tr>\n<tr>\n<td><strong>INCLUIDO<\/strong><\/td>\n<td>\n<table class=\"table table-bordered\" style=\"height: 62px;\" width=\"300\">\n<tbody>\n<tr>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Guia Profesional<\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Todo el material: Kayak, pala, chaleco salvavidas y neopreno.<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Agua y aperitivo.<\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Lugar seguro para tus pertenencias<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td><b>NO INCLUIDO<\/b><\/td>\n<td>\n<table class=\"table table-bordered\" style=\"height: 62px;\" width=\"300\">\n<tbody>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Transporte desde el hotel y vuelta, pero puede ser acordado por separado<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Fotograf\u00edas de la traves\u00eda, que tambien puede ser acordado por separado.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ven a descubrir la costa de Lisboa remando mientras te diviertes! No hay mejor manera de descubrir \u00bbCosta do Sol\u00bb(Cascais-Lisboa) que por el rio Tajo. Podr\u00e1s ver la costa, las fortalezas mar\u00edtimas y sus preciosas playas.<\/p>\n","protected":false},"featured_media":10280,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[147],"product_tag":[],"class_list":["post-2919","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categorizar","tour_category-actividades","tour_category-ambiente-familiar","tour_category-oeiras-es","tour_category-piraguismo-kayak","tour_category-snacks-incluidos-es","first","instock","taxable","shipping-taxable","purchasable","product-type-tour"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/2919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media\/10280"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media?parent=2919"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_brand?post=2919"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_cat?post=2919"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_tag?post=2919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}