{"id":3690,"date":"2019-01-12T16:10:20","date_gmt":"2019-01-12T16:10:20","guid":{"rendered":"https:\/\/borkyou.com\/product\/emergency-first-response\/"},"modified":"2019-04-15T08:57:37","modified_gmt":"2019-04-15T08:57:37","slug":"emergency-first-response","status":"publish","type":"product","link":"https:\/\/borkyou.com\/es\/producto\/emergency-first-response\/","title":{"rendered":"Emergency First Response"},"content":{"rendered":"<p><a href=\"https:\/\/borkyou.com\/wp-content\/uploads\/2019\/01\/efr-280x280-89.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3683 alignleft\" src=\"https:\/\/borkyou.com\/wp-content\/uploads\/2019\/01\/efr-280x280-89.jpg\" alt=\"\" width=\"181\" height=\"181\" srcset=\"https:\/\/borkyou.com\/wp-content\/uploads\/2019\/01\/efr-280x280-89.jpg 280w, https:\/\/borkyou.com\/wp-content\/uploads\/2019\/01\/efr-280x280-89-150x150.jpg 150w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><\/a><\/p>\n<p class=\"tw-data-text tw-ta tw-text-small\" dir=\"ltr\" data-placeholder=\"Translation\"><span lang=\"es\">Emergency First Response,\u00a0<\/span><span lang=\"es\">cuidados primarios y secundarios<\/span><span lang=\"es\">. Para quien pretende aprender sobre el soporte b\u00e1sico de vida. Si es buceador, necesitar\u00e1 este certificado para los cursos m\u00e1s avanzados del buceo, como el PADI Rescue Diver y el PADI Dive Master. El curso est\u00e1 basado en directrices m\u00e9dicas reconocidas internacionalmente y pretende aumentar su confianza y voluntad de responder ante una emergencia m\u00e9dica.<\/span><\/p>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-ta tw-text-small\" dir=\"ltr\" data-placeholder=\"Translation\"><span lang=\"es\">Se contar\u00e1 con dos sesiones de desarrollo de conocimientos y dos sesiones pr\u00e1cticas con uso de maniqu\u00ed, desfibrilador externo autom\u00e1tico y ox\u00edgeno de emergencia<\/span><\/p>\n<p><strong>INCLUIDO<\/strong><\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Todo el equipo necesario<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i><span lang=\"es\">Manual y DVD PADI<\/span><\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Seguro<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i><span lang=\"es\">Certificaci\u00f3n internacional PADI<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuidados primarios y secundarios. Buceador o no, aprender\u00e1 un importante soporte vital b\u00e1sico para responder ante una emergencia m\u00e9dica.<\/p>\n","protected":false},"featured_media":3934,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[804],"product_tag":[],"class_list":["post-3690","product","type-product","status-publish","has-post-thumbnail","product_cat-dive-es","tour_category-cursos-es","tour_category-cursos-de-buceo","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/3690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media\/3934"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media?parent=3690"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_brand?post=3690"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_cat?post=3690"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_tag?post=3690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}