{"id":6029,"date":"2020-10-31T11:52:46","date_gmt":"2020-10-31T11:52:46","guid":{"rendered":"https:\/\/borkyou.com\/product\/senderismo-en-san-miguel\/"},"modified":"2020-10-31T11:52:46","modified_gmt":"2020-10-31T11:52:46","slug":"senderismo-en-san-miguel","status":"publish","type":"product","link":"https:\/\/borkyou.com\/es\/tours\/senderismo-en-san-miguel\/","title":{"rendered":"Senderismo en San Miguel"},"content":{"rendered":"<h1 id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Tradu\u00e7\u00e3o\"><span lang=\"es\" tabindex=\"0\">Senderismo S\u00e3o Miguel | La Isla Verde<\/span><\/h1>\n<h1 class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: left;\" data-placeholder=\"Tradu\u00e7\u00e3o\">\u00a1Bienvenido a la isla de S\u00e3o Miguel! \u00a1Una regi\u00f3n de suntuosos paisajes, alojamientos y gastronom\u00eda!<\/h1>\n<h2 class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: left;\" data-placeholder=\"Tradu\u00e7\u00e3o\">Descubra S\u00e3o Miguel, un jard\u00edn en medio del Oc\u00e9ano Atl\u00e1ntico, con su exuberante naturaleza, senderos para caminatas en la selva tropical y sus impresionantes miradores sobre lagos de cr\u00e1teres azules, recordatorios geol\u00f3gicos de un pasado volc\u00e1nico.<\/h2>\n<table class=\"table table-borded tours-tabs__table\">\n<tbody>\n<tr>\n<td>\n<h3><strong>INCLUIDO<\/strong><\/h3>\n<\/td>\n<td>\n<h3><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Transportes<\/h3>\n<h3><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i> Todas las actividades: avistamiento de ballenas, senderismo, descubrimiento<\/h3>\n<h3><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i> 4 &#8211; Alojamiento y comida de alta calidad<\/h3>\n<h3><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Gu\u00eda de senderismo<\/h3>\n<h3><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Comidas desde la cena del d\u00eda 1 hasta el desayuno del d\u00eda 8<\/h3>\n<\/td>\n<\/tr>\n<\/tbody>\n<p><\/p>\n<h3 class=\"jhH5U r-ihkfwJv3nCBA\" data-rtid=\"ihkfwJv3nCBA\">Nuestra primera caminata nos llevar\u00e1 a una de las vistas m\u00e1s impresionantes de la isla: la Laguna de las 7 ciudades (Lagoa das 7 cidades), los lagos gemelos situados en el cr\u00e1ter de un volc\u00e1n inactivo, donde la Lagoa Azul (Blue Lake) y la Lagoa Verde (Green Lake) est\u00e1n conectadas por un angosto estrecho, atravesado por un puente. El Lago Canario y la Serra Devassa que caminaremos al d\u00eda siguiente se encuentra al sur de las 7 Cidades, es un sendero menos famoso pero igualmente hermoso.<br \/>\nLa segunda parte del viaje nos llevar\u00e1 a la antigua villa termal de Furnas, desde donde descubriremos otros cr\u00e1teres, como el Lago de Fuego, muchas fuentes termales, cascadas y picos con puntos elevados como el Pico do Ferro.<br \/><br \/>\nHay 28 especies de cet\u00e1ceos que se pueden encontrar en el Archipi\u00e9lago e intentaremos ver algunas ballenas, delfines junto con tortugas, aves marinas y otra fauna marina. S\u00e3o Miguel tambi\u00e9n es famoso por sus plantaciones de t\u00e9 y pi\u00f1a, que tambi\u00e9n visitaremos.<br \/>\nTerminaremos el viaje en la costa norte, visitaremos sus tesoros y nos daremos un buen ba\u00f1o en las piscinas naturales, antes de reunirnos para nuestra cena de despedida.<\/h3>\n<h4><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Sete Cidades: paseo por el cr\u00e1ter con impresionantes vistas de los lagos gemelos Lagoa Verde (el lago verde) y Lagoa Azul (el lago azul) y los dos lagos m\u00e1s peque\u00f1os del cr\u00e1ter Lagoa Santiago y Lagoa Rasa.< br \/><br \/>\n<i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Furnas: nade en manantiales a 98\u00ba Fahrenheit, hornos naturales y piscinas de lodo burbujeante en Furnas, antiguo pueblo balneario de S\u00e3o Mi-guel.<br \/>\n<i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Ponta Delgada: Capital de la isla desde mediados del siglo XVI, Ponta Delgada alberga hermosos ejemplos de arquitectura portuguesa.<\/h4>\n<\/table><table class=\"table table-borded tours-tabs__table\">\n<tbody>\n<tr>\n<td><strong>NO INCLUIDO<\/strong><\/td>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Vuelo\n<p><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Equipo<\/p><\/td>\n<\/tr>\n<\/tbody>\n<p><\/p>\n<h2><strong>Pr\u00f3ximas salidas<\/strong><\/h2>\n<p><strong>Rellene el siguiente formulario con sus datos de registro y nos pondremos en contacto con usted en breve.<\/strong><\/p>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-3962\"><form id=\"wpforms-form-3962\" class=\"wpforms-validate wpforms-form\" data-formid=\"3962\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/product\/6029\" data-token=\"d3f1f1d471246fd7af6064e06ff5bcc0\" data-token-time=\"1788345006\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-3962-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3962-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required\/><\/div><div id=\"wpforms-3962-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_3\">Phone number <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3962-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required\/><div class=\"wpforms-field-description\">(+country code) phone number<\/div><\/div><div id=\"wpforms-3962-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3962-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required\/><\/div><div id=\"wpforms-3962-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_2\">Your message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-3962-field_2\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-3962-field-hp\" class=\"wpforms-field-label\">Website<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-3962-field-hp\" class=\"wpforms-field-medium\"\/><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\"><div class=\"g-recaptcha\" data-sitekey=\"6LewO44UAAAAAFSiTlzwD7KcTdvtvonbTWkWfM5t\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"3962\"\/><input type=\"hidden\" name=\"page_title\" value=\"\"\/><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/6029\"\/><input type=\"hidden\" name=\"url_referer\" value=\"\"\/><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3962\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<\/table>","protected":false},"excerpt":{"rendered":"<p>\u00a1Descubra S\u00e3o Miguel, un jard\u00edn en medio del Oc\u00e9ano Atl\u00e1ntico, con su exuberante naturaleza, senderos para caminatas en la selva tropical y sus impresionantes miradores!<\/p>\n","protected":false},"featured_media":5032,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[147],"product_tag":[],"class_list":["post-6029","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categorizar","tour_category-portugal-hiking-kayaking-expeditions-es","first","instock","taxable","shipping-taxable","purchasable","product-type-tour"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/6029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media\/5032"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media?parent=6029"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_brand?post=6029"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_cat?post=6029"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_tag?post=6029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}