{"id":6030,"date":"2021-07-03T13:04:50","date_gmt":"2021-07-03T13:04:50","guid":{"rendered":"https:\/\/borkyou.com\/product\/viaje-de-buceo-en-la-isla-terceira-azores\/"},"modified":"2021-07-03T13:04:50","modified_gmt":"2021-07-03T13:04:50","slug":"viaje-de-buceo-en-la-isla-terceira-azores","status":"publish","type":"product","link":"https:\/\/borkyou.com\/es\/tours\/viaje-de-buceo-en-la-isla-terceira-azores\/","title":{"rendered":"Viaje de buceo en la Isla Terceira, Azores"},"content":{"rendered":"<h1 id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Tradu\u00e7\u00e3o\"><span lang=\"en\" tabindex=\"0\">Viaje de buceo<\/span><\/h1>\n<h1 class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Tradu\u00e7\u00e3o\"><span lang=\"en\" tabindex=\"0\">Isla Terceira<br \/>\n<\/span><span lang=\"es\" tabindex=\"0\">2021\/2022<\/span><\/h1>\n<p style=\"text-align: center;\"><iframe title=\"Mergulho na Ilha Terceira, A\u00e7ores | BORK\" src=\"https:\/\/www.youtube.com\/embed\/ZU_ZuZhyjxw?feature=oembed\" width= \"411\" height=\"231\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2 class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: left;\" data-placeholder=\"Tradu\u00e7\u00e3o\">Rumbo a&#8230; \u00a1Isla Terceira! Integrada en el \u00abGrupo Central\u00bb, la isla Terceira, as\u00ed como las 9 islas del archipi\u00e9lago de las Azores, ofrece condiciones excepcionales para el buceo!<\/h2>\n<p>Comenzando en Angra do Hero\u00edsmo, ciudad hist\u00f3rica clasificada como Patrimonio de la Humanidad por la UNESCO, hay varios lugares que prometen impresionar a nuestros buceadores. Considerado el segundo lugar del mundo con mayor n\u00famero de naufragios de la \u00e9poca de los Descubrimientos y m\u00e1s de 40 anclas, integrado en el Parque Arqueol\u00f3gico Subacu\u00e1tico de la bah\u00eda de Angra do Hero\u00edsmo, tenemos un aut\u00e9ntico museo submarino justo al lado de la tranquila bah\u00eda de Angra do Hero\u00edsmo. \u00a1Ven a visitar el \u00abCemit\u00e9rio das \u00c2ncoras\u00bb!<\/p>\n<p>Pero hay m\u00e1s para ver m\u00e1s all\u00e1 de los naufragios. Las famosas cuevas submarinas de la isla Terceira prometen sorprenderte. La vida marina costera se caracteriza por la presencia de simp\u00e1ticos meros, curiosos card\u00famenes de peces cerdo (<em>Orthopristis chrysoptera<\/em>), garabatos, reinas, pulpos y varias especies de morenas y nudibranquios, con paredes cubiertas por camarones narvales ( <em>Plesionika narval<\/em>).<br \/>\nAumentando la profundidad podemos observar grandes mantarrayas (<em>Dasyatis pastinaca<\/em>), grandes card\u00famenes de salemas pargos (<em>Sapra Salpa<\/em>), br\u00f3tolas (<em>Phycis phycis<\/em>). Y precisamente en septiembre tenemos muchas posibilidades de encontrar las majestuosas rayas \u00e1guila.<\/p>\n<p>Todos los sitios de buceo est\u00e1n repletos de vida marina. Con las condiciones de gran visibilidad caracter\u00edsticas de las Azores, que aqu\u00ed oscilan entre los 10 y los 40 metros, la temperatura del agua en torno a los 19\u00baC al final de la temporada, utilizamos trajes h\u00famedos y semisecos de 7 mm para explorar el fondo del mar.<\/ p><\/p>\n<p>&nbsp;<\/p>\n<h1 class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Tradu\u00e7\u00e3o\">\u00a1\u00danete a nosotros en una aventura inolvidable m\u00e1s!<\/h1>\n<p>&nbsp;<\/p>\n<table class=\"table table-borded tours-tabs__table\">\n<tbody>\n<tr>\n<td><strong>INCLUIDO<\/strong><\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i> 7 noches en Habitaci\u00f3n Doble Est\u00e1ndar en Pousada Forte Angra do Hero\u00edsmo\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i> 10 inmersiones, incluyendo \u00abCemit\u00e9rio das \u00c2ncoras\u00bb, \u00abGruta do Ilh\u00e9u das Cabras\u00bb y \u00abFradinhos\u00bb<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i> Todo el equipo necesario<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i> Gu\u00eda de buceo<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Todas las comidas entre la cena del primer s\u00e1bado hasta el almuerzo del \u00faltimo s\u00e1bado<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Seguro<\/p><\/td>\n<\/tr>\n<tr>\n<td><strong>NO INCLUIDO<\/strong><\/td>\n<td><i class=\"fa fa-times icon-tick icon-tick--off\"><\/i>Vuelo*<\/td>\n<\/tr>\n<\/tbody>\n<p><\/p>\n<p>(*)Vuelos alrededor de 65\u20ac<\/p>\n<h2>Pr\u00f3ximos viajes<\/h2>\n<\/table><table class=\"table table-borded tours-tabs__table\">\n<tbody>\n<tr>\n<td><strong>09\/03\/2022 &#8211; 09\/10\/2022<\/strong><\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Disponible<\/td>\n<\/tr>\n<tr>\n<td><strong>24\/09\/2022 &#8211; 01\/10\/2022<\/strong><\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Disponible<\/td>\n<\/tr>\n<\/tbody>\n<p><\/p>\n<p>Solicite m\u00e1s informaci\u00f3n y otros detalles a bork@borkyou.com o rellene el formulario de contacto.<\/p>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-3962\"><form id=\"wpforms-form-3962\" class=\"wpforms-validate wpforms-form\" data-formid=\"3962\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/product\/6030\" data-token=\"d3f1f1d471246fd7af6064e06ff5bcc0\" data-token-time=\"1788340766\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-3962-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3962-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required\/><\/div><div id=\"wpforms-3962-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_3\">Phone number <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3962-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" required\/><div class=\"wpforms-field-description\">(+country code) phone number<\/div><\/div><div id=\"wpforms-3962-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3962-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required\/><\/div><div id=\"wpforms-3962-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-3962-field_2\">Your message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-3962-field_2\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-3962-field-hp\" class=\"wpforms-field-label\">Email<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-3962-field-hp\" class=\"wpforms-field-medium\"\/><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\"><div class=\"g-recaptcha\" data-sitekey=\"6LewO44UAAAAAFSiTlzwD7KcTdvtvonbTWkWfM5t\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"3962\"\/><input type=\"hidden\" name=\"page_title\" value=\"\"\/><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/6030\"\/><input type=\"hidden\" name=\"url_referer\" value=\"\"\/><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3962\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<\/table>","protected":false},"excerpt":{"rendered":"<p>\u00a1Ven a bucear con nuestro equipo en los sitios de buceo m\u00e1s incre\u00edbles de las Azores! Quedar\u00e1s deslumbrado por todo lo que te rodea, adem\u00e1s de la hermosa isla de Santa Mar\u00eda, lo mejor ser\u00e1n sus cristalinas aguas azules con visibilidad de m\u00e1s de 40 metros, llenas de vida submarina!<\/p>\n","protected":false},"featured_media":5779,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[147],"product_tag":[],"class_list":["post-6030","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categorizar","tour_category-dive-es","tour_category-viaje-de-buceo","first","instock","taxable","shipping-taxable","purchasable","product-type-tour"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product\/6030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media\/5779"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/media?parent=6030"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_brand?post=6030"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_cat?post=6030"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/es\/wp-json\/wp\/v2\/product_tag?post=6030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}