{"id":3007,"date":"2018-12-12T17:54:46","date_gmt":"2018-12-12T17:54:46","guid":{"rendered":"https:\/\/borkyou.com\/?post_type=product&#038;p=3007"},"modified":"2019-01-06T15:37:46","modified_gmt":"2019-01-06T15:37:46","slug":"expedicao-de-kayak-por-lisboa","status":"publish","type":"product","link":"https:\/\/borkyou.com\/pt-pt\/tours\/expedicao-de-kayak-por-lisboa\/","title":{"rendered":"Expedi\u00e7\u00e3o de Kayak por Lisboa"},"content":{"rendered":"<h1>Descubra a costa de Lisboa enquanto rema!<\/h1>\n<p>Lisboa \u00e9 um tesouro resguardado pelo Rio Tejo e o Oceano Atl\u00e2ntico que poder\u00e1 apreciar atrav\u00e9s da sua magn\u00edfica costa.<br \/>\nA expedi\u00e7\u00e3o ter\u00e1 in\u00edcio em Cascais, no Oceano Atl\u00e2ntico, onde remar\u00e1 ao longo de uma das costas urbanas mais bonitas da Europa, at\u00e9 alcan\u00e7ar o Rio Tejo. Ficar\u00e1 impressionado com os castelos, pal\u00e1cios, vilas e fortes. Ap\u00f3s admirar um dos marcos hist\u00f3ricos de Bel\u00e9m, o Padr\u00e3o dos Descobrimentos, prosseguiremos em dire\u00e7\u00e3o a Sesimbra \u00e0 descoberta do Parque Natural e da sua costa \u00fanica, at\u00e9 chegarmos \u00e0 Pen\u00ednsula de Tr\u00f3ia.<\/p>\n<table class=\"table table-bordered tours-tabs__table\" style=\"height: 420px;\" width=\"1232\">\n<tbody>\n<tr>\n<td><strong>INCLU\u00cdDO<\/strong><\/td>\n<td><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Guia<i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Transportes\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Seguro<\/p>\n<p><i class=\"fa fa-check icon-tick icon-tick--on\"><\/i>Alojamento com pens\u00e3o completa<\/p><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Descubra a costa de Lisboa enquanto rema!<\/p>\n","protected":false},"featured_media":8450,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[146],"product_tag":[],"class_list":["post-3007","product","type-product","status-publish","has-post-thumbnail","product_cat-sem-categoria","tour_category-expedicoes","first","instock","taxable","shipping-taxable","purchasable","product-type-tour"],"_links":{"self":[{"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/product\/3007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3007"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=3007"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=3007"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/borkyou.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=3007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}